{"id":12402,"date":"2025-09-26T14:35:08","date_gmt":"2025-09-26T14:35:08","guid":{"rendered":"https:\/\/www.polifactory.polimi.it\/?post_type=community&#038;p=12402"},"modified":"2026-01-13T14:53:57","modified_gmt":"2026-01-13T14:53:57","slug":"valentino-stella","status":"publish","type":"community","link":"https:\/\/www.polifactory.polimi.it\/en\/community\/valentino-stella\/","title":{"rendered":"Valentino Stella"},"content":{"rendered":"[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;32&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;3\/5&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;40&#8243;][vc_raw_html css=&#8221;&#8221; el_class=&#8221;foto-singlepage-staff&#8221;]JTVCZmVhdHVyZWRfaW1hZ2UlNUQ=[\/vc_raw_html][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;20&#8243;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221; el_class=&#8221;title-singlepage-staff&#8221;]\n<h2>Valentino Stella<\/h2>\n[\/vc_column_text][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221; el_class=&#8221;subtitle-singlepage-staff&#8221;]\n<h4><span data-olk-copy-source=\"MessageBody\">Research Associate<\/span><\/h4>\n[\/vc_column_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;20&#8243;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<p dir=\"ltr\">An industrial designer, he obtained a Master&#8217;s Degree in Integrated Product Design from the Politecnico di Milano in 2023 with a thesis focused on the design of an environmental monitoring station for social farming in urban spaces. During his academic career, he obtained a diploma from the <a href=\"https:\/\/www.asp-poli.it\/\">Alta Scuola Politecnica<\/a>, a multidisciplinary programme of excellence offered by the Politecnico di Milano and the Politecnico di Torino.<br \/>\nAfter an internship that began in December 2023, he is currently collaborating on research activities at Polifactory.<\/p>\n[\/vc_column_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;40&#8243;][nectar_icon icon_family=&#8221;fontawesome&#8221; icon_style=&#8221;soft-bg&#8221; icon_color_type=&#8221;color_scheme&#8221; icon_color=&#8221;Accent-Color&#8221; open_new_tab=&#8221;true&#8221; icon_padding=&#8221;20px&#8221; pointer_events=&#8221;all&#8221; icon_fontawesome=&#8221;fa fa-linkedin-square&#8221; url=&#8221;https:\/\/www.linkedin.com\/in\/valentino-stella\/&#8221; screen_reader_text=&#8221;LinkedIn&#8221; icon_size=&#8221;24&#8243; margin_left=&#8221;8&#8243; margin_right=&#8221;8&#8243;][nectar_icon icon_family=&#8221;fontawesome&#8221; icon_style=&#8221;soft-bg&#8221; icon_color_type=&#8221;color_scheme&#8221; icon_color=&#8221;Accent-Color&#8221; open_new_tab=&#8221;true&#8221; icon_padding=&#8221;20px&#8221; pointer_events=&#8221;all&#8221; icon_fontawesome=&#8221;fa fa-book&#8221; screen_reader_text=&#8221;Research Gate&#8221; icon_size=&#8221;24&#8243; margin_left=&#8221;8&#8243; margin_right=&#8221;8&#8243;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;center&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/5&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;center&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; line_type=&#8221;Full Width Line&#8221; line_alignment=&#8221;default&#8221; line_thickness=&#8221;1&#8243; divider_color=&#8221;default&#8221; divider_opacity=&#8221;100&#8243; animate=&#8221;&#8221; custom_height=&#8221;80&#8243; custom_height_tablet=&#8221;&#8221; custom_height_phone=&#8221;&#8221; custom_line_width=&#8221;&#8221; delay=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;80&#8243;][\/vc_column][\/vc_row]\n","protected":false},"featured_media":10715,"template":"","categories":[106,144],"tags":[],"class_list":["post-12402","community","type-community","status-publish","has-post-thumbnail","category-staff-en","category-staff"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Valentino Stella - Polifactory<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.polifactory.polimi.it\/en\/community\/valentino-stella\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Valentino Stella - Polifactory\" \/>\n<meta property=\"og:description\" content=\"[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;32&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243;...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.polifactory.polimi.it\/en\/community\/valentino-stella\/\" \/>\n<meta property=\"og:site_name\" content=\"Polifactory\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/polifactory\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-13T14:53:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.polifactory.polimi.it\/wp-content\/uploads\/2024\/08\/Foto-cropped-Valentino-Stella-min-1024x1024.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.polifactory.polimi.it\\\/en\\\/community\\\/valentino-stella\\\/\",\"url\":\"https:\\\/\\\/www.polifactory.polimi.it\\\/en\\\/community\\\/valentino-stella\\\/\",\"name\":\"Valentino Stella - Polifactory\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.polifactory.polimi.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.polifactory.polimi.it\\\/en\\\/community\\\/valentino-stella\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.polifactory.polimi.it\\\/en\\\/community\\\/valentino-stella\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.polifactory.polimi.it\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Foto-cropped-Valentino-Stella-min.png\",\"datePublished\":\"2025-09-26T14:35:08+00:00\",\"dateModified\":\"2026-01-13T14:53:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.polifactory.polimi.it\\\/en\\\/community\\\/valentino-stella\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.polifactory.polimi.it\\\/en\\\/community\\\/valentino-stella\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.polifactory.polimi.it\\\/en\\\/community\\\/valentino-stella\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.polifactory.polimi.it\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Foto-cropped-Valentino-Stella-min.png\",\"contentUrl\":\"https:\\\/\\\/www.polifactory.polimi.it\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Foto-cropped-Valentino-Stella-min.png\",\"width\":3472,\"height\":3472},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.polifactory.polimi.it\\\/en\\\/community\\\/valentino-stella\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.polifactory.polimi.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Valentino Stella\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.polifactory.polimi.it\\\/#website\",\"url\":\"https:\\\/\\\/www.polifactory.polimi.it\\\/\",\"name\":\"Polifactory\",\"description\":\"Il makerspace-fablab del Politecnico di Milano\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.polifactory.polimi.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Valentino Stella - Polifactory","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.polifactory.polimi.it\/en\/community\/valentino-stella\/","og_locale":"en_US","og_type":"article","og_title":"Valentino Stella - Polifactory","og_description":"[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;32&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243;...","og_url":"https:\/\/www.polifactory.polimi.it\/en\/community\/valentino-stella\/","og_site_name":"Polifactory","article_publisher":"https:\/\/www.facebook.com\/polifactory","article_modified_time":"2026-01-13T14:53:57+00:00","og_image":[{"width":1024,"height":1024,"url":"https:\/\/www.polifactory.polimi.it\/wp-content\/uploads\/2024\/08\/Foto-cropped-Valentino-Stella-min-1024x1024.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.polifactory.polimi.it\/en\/community\/valentino-stella\/","url":"https:\/\/www.polifactory.polimi.it\/en\/community\/valentino-stella\/","name":"Valentino Stella - Polifactory","isPartOf":{"@id":"https:\/\/www.polifactory.polimi.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.polifactory.polimi.it\/en\/community\/valentino-stella\/#primaryimage"},"image":{"@id":"https:\/\/www.polifactory.polimi.it\/en\/community\/valentino-stella\/#primaryimage"},"thumbnailUrl":"https:\/\/www.polifactory.polimi.it\/wp-content\/uploads\/2024\/08\/Foto-cropped-Valentino-Stella-min.png","datePublished":"2025-09-26T14:35:08+00:00","dateModified":"2026-01-13T14:53:57+00:00","breadcrumb":{"@id":"https:\/\/www.polifactory.polimi.it\/en\/community\/valentino-stella\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.polifactory.polimi.it\/en\/community\/valentino-stella\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.polifactory.polimi.it\/en\/community\/valentino-stella\/#primaryimage","url":"https:\/\/www.polifactory.polimi.it\/wp-content\/uploads\/2024\/08\/Foto-cropped-Valentino-Stella-min.png","contentUrl":"https:\/\/www.polifactory.polimi.it\/wp-content\/uploads\/2024\/08\/Foto-cropped-Valentino-Stella-min.png","width":3472,"height":3472},{"@type":"BreadcrumbList","@id":"https:\/\/www.polifactory.polimi.it\/en\/community\/valentino-stella\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.polifactory.polimi.it\/en\/"},{"@type":"ListItem","position":2,"name":"Valentino Stella"}]},{"@type":"WebSite","@id":"https:\/\/www.polifactory.polimi.it\/#website","url":"https:\/\/www.polifactory.polimi.it\/","name":"Polifactory","description":"Il makerspace-fablab del Politecnico di Milano","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.polifactory.polimi.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.polifactory.polimi.it\/en\/wp-json\/wp\/v2\/community\/12402","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.polifactory.polimi.it\/en\/wp-json\/wp\/v2\/community"}],"about":[{"href":"https:\/\/www.polifactory.polimi.it\/en\/wp-json\/wp\/v2\/types\/community"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.polifactory.polimi.it\/en\/wp-json\/wp\/v2\/media\/10715"}],"wp:attachment":[{"href":"https:\/\/www.polifactory.polimi.it\/en\/wp-json\/wp\/v2\/media?parent=12402"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.polifactory.polimi.it\/en\/wp-json\/wp\/v2\/categories?post=12402"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.polifactory.polimi.it\/en\/wp-json\/wp\/v2\/tags?post=12402"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}